{"id":31500,"date":"2026-02-11T11:30:32","date_gmt":"2026-02-11T11:30:32","guid":{"rendered":"https:\/\/www.complycube.com\/?p=31500"},"modified":"2026-02-11T11:21:03","modified_gmt":"2026-02-11T11:21:03","slug":"outil-de-flux-de-travail-kyc","status":"publish","type":"post","link":"https:\/\/www.complycube.com\/fr\/kyc-workflow-tool\/","title":{"rendered":"ComplyCube permet de faire confiance \u00e0 grande \u00e9chelle gr\u00e2ce \u00e0 son outil de flux de travail KYC"},"content":{"rendered":"<p>LONDRES, 11 F\u00c9VRIER 2026 \u2013 Face \u00e0 l\u2019acc\u00e9l\u00e9ration de la fraude \u00e0 l\u2019identit\u00e9 synth\u00e9tique, l\u2019IA g\u00e9n\u00e9rative facilite la mise \u00e0 l\u2019\u00e9chelle de la tromperie. Aujourd\u2019hui encore, la R\u00e9serve f\u00e9d\u00e9rale am\u00e9ricaine signale r\u00e9guli\u00e8rement ce type de fraude, et les institutions financi\u00e8res attribuent plus de 401\u00a0000 milliards de dollars de fraudes \u00e0 l\u2019ouverture de compte \u00e0 des attaques par usurpation d\u2019identit\u00e9. Face \u00e0 cette situation d\u2019urgence,\u00a0<a href=\"https:\/\/www.complycube.com\/fr\/\">ComplyCube<\/a>\u00a0a lanc\u00e9 un\u00a0<a title=\"\" href=\"https:\/\/www.complycube.com\/fr\/solutions\/suite-de-conformite\/flux-de-travail-kyc\/\">outil de flux de travail KYC sans code<\/a>, \u00c9galement connu sous le nom d&#039;outil d&#039;orchestration des flux de travail KYC, il aide les \u00e9quipes de conformit\u00e9 \u00e0 cr\u00e9er, d\u00e9ployer et orchestrer des flux de travail KYC sans rencontrer de difficult\u00e9s techniques.<\/p>\r\n\r\n\r\n<p>Cette pression du \u201c pourquoi maintenant \u201d ne se limite pas aux seules banques. Les parcours frauduleux commencent de plus en plus hors plateforme et les autorit\u00e9s r\u00e9glementaires exigent sans cesse des contr\u00f4les d\u00e9montrables et v\u00e9rifiables tout au long du processus d&#039;ouverture de compte et de gestion du cycle de vie des comptes.<\/p>\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Pourquoi les processus de conformit\u00e9 doivent changer<\/h2>\r\n\r\n\r\n<p>Les syst\u00e8mes d&#039;int\u00e9gration traditionnels sont fragment\u00e9s et rigides, ce qui rend difficile pour\u00a0<a href=\"https:\/\/www.complycube.com\/fr\/cas-dutilisation\/profession\/responsables-de-la-conformite\/\">\u00e9quipes de conformit\u00e9<\/a>\u00a0Pour garantir la coh\u00e9rence et la rapidit\u00e9 \u00e0 grande \u00e9chelle, il est essentiel de disposer d&#039;outils de gestion des flux de travail KYC unifi\u00e9s. En effet, la v\u00e9rification des clients n\u00e9cessite souvent de combiner diff\u00e9rents services et de s&#039;appuyer sur l&#039;ing\u00e9nierie pour adapter les flux de travail, ce qui ralentit les d\u00e9lais de r\u00e9ponse aux \u00e9volutions r\u00e9glementaires et aux nouveaux risques de fraude.<\/p>\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"536\" class=\"wp-image-31510\" src=\"https:\/\/www.complycube.com\/wp-content\/uploads\/2026\/02\/why-compliance-workflows-must-change-1-1024x536.png\" alt=\"Infographie intitul\u00e9e \u201c Pourquoi les flux de travail de conformit\u00e9 doivent changer \u201d montrant les principaux facteurs d&#039;un outil de flux de travail KYC et d&#039;un outil d&#039;orchestration de flux de travail KYC : $23B\u2192$58B co\u00fbt de la fraude (2025-2030), 200 actions d&#039;application de la loi au 1er trimestre de l&#039;exercice 2025, 44,1% luttent contre les changements r\u00e9glementaires, 82% investissent dans la technologie de conformit\u00e9 et 77% affirment que la complexit\u00e9 nuit \u00e0 la croissance, renfor\u00e7ant ainsi le besoin d&#039;une orchestration des flux de travail KYC.\" srcset=\"https:\/\/www.complycube.com\/wp-content\/uploads\/2026\/02\/why-compliance-workflows-must-change-1-1024x536.png 1024w, https:\/\/www.complycube.com\/wp-content\/uploads\/2026\/02\/why-compliance-workflows-must-change-1-300x157.png 300w, https:\/\/www.complycube.com\/wp-content\/uploads\/2026\/02\/why-compliance-workflows-must-change-1-768x402.png 768w, https:\/\/www.complycube.com\/wp-content\/uploads\/2026\/02\/why-compliance-workflows-must-change-1-18x9.png 18w, https:\/\/www.complycube.com\/wp-content\/uploads\/2026\/02\/why-compliance-workflows-must-change-1.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n\r\n\r\n<p>Il est crucial de noter que les escroqueries actuelles proviennent de sources autres que les processus d&#039;int\u00e9gration des clients. Selon les rapports de Juniper Research, les pertes mondiales li\u00e9es \u00e0 la fraude pour les institutions financi\u00e8res devraient passer de 1\u00a0700 milliards de dollars en 2025 \u00e0 1\u00a0700 milliards de dollars en 2030. Cela repr\u00e9sente une augmentation de 1\u00a0531\u00a0000 milliards de dollars en cinq ans. Cette tendance implique que les mesures de contr\u00f4le ne peuvent rester statiques ni cloisonn\u00e9es si les menaces sont multicanaux et \u00e9voluent rapidement.<\/p>\r\n\r\n\r\n<p>Les difficult\u00e9s les plus courantes sont les suivantes\u00a0:<\/p>\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n\t<li><strong>La fraude \u00e0 l&#039;identit\u00e9 synth\u00e9tique est en hausse<\/strong>, ce qui n\u00e9cessite des \u00e9tapes de v\u00e9rification suppl\u00e9mentaires<\/li>\r\n\r\n\r\n\t<li><strong>Examens manuels et retards<\/strong>, ce qui entra\u00eene une perte de clients et des frais g\u00e9n\u00e9raux d&#039;exploitation.<\/li>\r\n\r\n\r\n\t<li><strong>Logique incoh\u00e9rente entre les produits et les march\u00e9s<\/strong>, risque de non-conformit\u00e9 croissant<\/li>\r\n<\/ul>\r\n\r\n\r\n<p>De plus, r\u00e9soudre ces probl\u00e8mes implique de donner aux \u00e9quipes un meilleur contr\u00f4le sur l&#039;orchestration de leur processus KYC. Ainsi, lorsqu&#039;elles peuvent concevoir et mettre \u00e0 jour elles-m\u00eames la logique d&#039;int\u00e9gration, elles ne d\u00e9pendent plus des retards d&#039;ing\u00e9nierie ni des longs cycles de publication. Cette autonomie acc\u00e9l\u00e8re la mise sur le march\u00e9 des nouvelles r\u00e8gles ou strat\u00e9gies de gestion des risques. Par cons\u00e9quent, elle garantit la coh\u00e9rence, la conformit\u00e9 et la r\u00e9activit\u00e9 des flux de v\u00e9rification face aux nouvelles menaces.<\/p>\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Outil de flux de travail KYC en temps r\u00e9el pour les parcours d&#039;identit\u00e9 structur\u00e9s<\/h2>\r\n\r\n\r\n<p>Dans un\u00a0<a href=\"https:\/\/assets.kpmg.com\/content\/dam\/kpmgsites\/sg\/pdf\/2024\/01\/stepping-up-to-a-new-level.pdf.coredownload.inline.pdf\">rapport de KPMG<\/a>, Selon 34% des responsables de la conformit\u00e9, les nouvelles exigences r\u00e9glementaires constituent le principal d\u00e9fi en mati\u00e8re de conformit\u00e9 pour les deux prochaines ann\u00e9es.\u00a0<a href=\"https:\/\/www.complycube.com\/fr\/solutions\/suite-de-conformite\/flux-de-travail-kyc\/\">Outil de flux de travail KYC<\/a>\u00a0Cette solution int\u00e8gre les contr\u00f4les d&#039;identit\u00e9, les signaux de fraude et la logique d\u00e9cisionnelle dans un flux orchestr\u00e9. Elle permet aux \u00e9quipes de conformit\u00e9 de concevoir et de d\u00e9ployer des processus KYC structur\u00e9s, adapt\u00e9s aux niveaux de risque, aux types d&#039;utilisateurs et aux r\u00e9glementations sp\u00e9cifiques \u00e0 chaque juridiction. Elle assure une mise \u00e0 jour rapide en cas d&#039;\u00e9volution des recommandations ou des tendances en mati\u00e8re de menaces.<\/p>\r\n\r\n\r\n<p>Les \u00e9quipes peuvent :<\/p>\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n\t<li><strong>D\u00e9finir les voies d&#039;escalade<\/strong>\u00a0utilisation de signaux de risque dynamiques<\/li>\r\n\r\n\r\n\t<li><strong>Cartographier l&#039;identit\u00e9, la lutte contre le blanchiment d&#039;argent et les contr\u00f4les de fraude<\/strong>\u00a0en un seul voyage<\/li>\r\n\r\n\r\n\t<li><strong>Mettez \u00e0 jour les flux de travail instantan\u00e9ment<\/strong>\u00a0en r\u00e9ponse \u00e0 l&#039;\u00e9volution de la r\u00e9glementation<\/li>\r\n<\/ul>\r\n\r\n\r\n<p>Cela r\u00e9duit la d\u00e9pendance \u00e0 l&#039;\u00e9gard de l&#039;ing\u00e9nierie. Une v\u00e9rification KYC <a href=\"https:\/\/www.complycube.com\/fr\/logiciel-de-flux-de-travail-de-conformite-aml-sans-code\/\">outil de flux de travail<\/a>\u00a0Cet outil permet aux responsables de la conformit\u00e9 d&#039;adapter plus rapidement les parcours d&#039;int\u00e9gration. Il favorise une r\u00e9ponse plus rapide aux \u00e9volutions r\u00e9glementaires tout en am\u00e9liorant l&#039;efficacit\u00e9 op\u00e9rationnelle, garantissant ainsi la conformit\u00e9 aux politiques internes et aux exigences l\u00e9gales. Cet outil d&#039;orchestration des flux de travail KYC s&#039;inscrit \u00e9galement dans les grandes orientations du secteur gr\u00e2ce \u00e0 la mise en place de contr\u00f4les multicouches, l&#039;am\u00e9lioration de la d\u00e9tection et le renforcement de la pr\u00e9paration op\u00e9rationnelle face \u00e0 l&#039;\u00e9volution de la fraude \u00e0 l&#039;identit\u00e9 synth\u00e9tique.<\/p>\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Coh\u00e9rence des outils de flux de travail KYC sans goulots d&#039;\u00e9tranglement techniques<\/h2>\r\n\r\n\r\n<p>Sur les principaux march\u00e9s mondiaux de la conformit\u00e9, l&#039;orchestration des processus KYC est de plus en plus confi\u00e9e aux infrastructures publiques. L&#039;UE met simultan\u00e9ment en place un r\u00e9gime d&#039;identit\u00e9 num\u00e9rique \u00e0 l&#039;\u00e9chelle du continent (eIDAS 2.0) et d\u00e9ploie un corpus r\u00e9glementaire unique en mati\u00e8re de lutte contre le blanchiment d&#039;argent (LCB). Elle instaure \u00e9galement un nouveau superviseur central (AMLA) charg\u00e9 d&#039;harmoniser la v\u00e9rification d&#039;identit\u00e9 et son application au-del\u00e0 des fronti\u00e8res. Parall\u00e8lement, le Royaume-Uni a adopt\u00e9 une approche similaire, transformant son cadre de confiance en mati\u00e8re d&#039;identit\u00e9 num\u00e9rique en r\u00e8gles l\u00e9gislatives \u00e0 compter du 1er d\u00e9cembre 2025, \u00e9tablissant ainsi un cadre juridique de r\u00e9f\u00e9rence pour l&#039;identit\u00e9 num\u00e9rique r\u00e9utilisable dans le secteur priv\u00e9.<\/p>\r\n\r\n\r\n<p>Peu apr\u00e8s, les \u00c9tats-Unis ont embo\u00eet\u00e9 le pas\u00a0: le FinCEN a \u00e9largi le p\u00e9rim\u00e8tre de la lutte contre le blanchiment d\u2019argent en int\u00e9grant les conseillers en investissement \u00e0 son programme LBC\/FT et \u00e0 son dispositif de d\u00e9claration des op\u00e9rations suspectes. L\u2019Australie et le Canada ont rapidement modernis\u00e9 leurs r\u00e9glementations afin d\u2019\u00e9tendre et de renforcer leurs obligations en mati\u00e8re de lutte contre le blanchiment d\u2019argent. Ce changement est g\u00e9n\u00e9ralis\u00e9.\u00a0<\/p>\r\n\r\n\r\n<p>Par cons\u00e9quent, le maintien d&#039;une coh\u00e9rence\u00a0<a href=\"https:\/\/www.complycube.com\/fr\/cas-dutilisation\/traiter\/integration-des-clients\/\">int\u00e9gration<\/a>\u00a0Offrir une exp\u00e9rience utilisateur coh\u00e9rente sur diff\u00e9rentes plateformes et r\u00e9gions est complexe lorsque chaque flux repose sur une logique cod\u00e9e en dur. Par exemple, l&#039;outil d&#039;orchestration de flux de travail KYC sans code de ComplyCube permet aux responsables de la conformit\u00e9 de mettre \u00e0 jour directement les parcours clients, garantissant ainsi l&#039;alignement des politiques sans intervention des d\u00e9veloppeurs.\u00a0<\/p>\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"536\" class=\"wp-image-31501\" src=\"https:\/\/www.complycube.com\/wp-content\/uploads\/2026\/02\/workflows-1024x536.png\" alt=\"Une banni\u00e8re portant la mention \u201c Con\u00e7u pour les \u00e9quipes de conformit\u00e9, pas pour les d\u00e9veloppeurs \u201d et des indicateurs cl\u00e9s de performance (KPI) affichant \u201c 0 sprint de d\u00e9veloppement\/mois \u201d, \u201c Lancement de flux de travail KYC 3 fois plus rapide \u201d, \u201c Temps d&#039;int\u00e9gration inf\u00e9rieur \u00e0 10 minutes \u201d et \u201c Conformit\u00e9 \u00e0 la norme 100% \u201d mettent en avant un outil de flux de travail KYC sans code et un outil d&#039;orchestration de flux de travail KYC permettant des lancements plus rapides, une d\u00e9pendance r\u00e9duite \u00e0 l&#039;ing\u00e9nierie et une orchestration de flux de travail KYC auditable.\" srcset=\"https:\/\/www.complycube.com\/wp-content\/uploads\/2026\/02\/workflows-1024x536.png 1024w, https:\/\/www.complycube.com\/wp-content\/uploads\/2026\/02\/workflows-300x157.png 300w, https:\/\/www.complycube.com\/wp-content\/uploads\/2026\/02\/workflows-768x402.png 768w, https:\/\/www.complycube.com\/wp-content\/uploads\/2026\/02\/workflows-18x9.png 18w, https:\/\/www.complycube.com\/wp-content\/uploads\/2026\/02\/workflows.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n\r\n\r\n<p>Compte tenu de cette approche en libre-service, les \u00e9quipes peuvent\u00a0:\u00a0<\/p>\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n\t<li><strong>D\u00e9ployer des flux sp\u00e9cifiques \u00e0 la r\u00e9gion et au produit<\/strong>\u00a0qui font respecter les normes mondiales<\/li>\r\n\r\n\r\n\t<li><strong>Assurer une application uniforme des contr\u00f4les<\/strong>\u00a0pour diff\u00e9rents profils de risque<\/li>\r\n\r\n\r\n\t<li><strong>Mettez en \u0153uvre les changements imm\u00e9diatement.<\/strong>, contr\u00f4lant leur propre gouvernance des versions<\/li>\r\n<\/ul>\r\n\r\n\r\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\r\n<p>Les flux de travail permettent aux \u00e9quipes de conformit\u00e9 de disposer des outils n\u00e9cessaires pour travailler plus rapidement.<\/p>\r\n<\/blockquote>\r\n\r\n\r\n<p>Directeur des produits chez ComplyCube,\u00a0<a href=\"https:\/\/www.linkedin.com\/in\/harryvaratharasan\/\">Harry Varatharasan<\/a>\u00a0Il poursuit en disant\u00a0: \u201c\u00a0Notre outil d\u2019orchestration des flux de travail KYC permet aux \u00e9quipes de cr\u00e9er et de mettre \u00e0 jour ces flux en temps r\u00e9el. Cette agilit\u00e9 les aide \u00e0 rester conformes tout en offrant un processus d\u2019int\u00e9gration plus efficace.\u00a0\u201d<\/p>\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Pistes d&#039;audit compl\u00e8tes pour la supervision op\u00e9rationnelle<\/h2>\r\n\r\n\r\n<p>Chaque orchestration de flux de travail KYC est ex\u00e9cut\u00e9e comme une session unique qui capture\u00a0<a href=\"https:\/\/www.complycube.com\/fr\/cas-dutilisation\/traiter\/verification-didentite\/\">chaque \u00e9tape de v\u00e9rification<\/a>\u00a0et une prise de d\u00e9cision en temps r\u00e9el. Cette structure organis\u00e9e facilite les audits, simplifie les enqu\u00eates et offre aux \u00e9quipes de conformit\u00e9 une meilleure visibilit\u00e9 sur les performances des contr\u00f4les d&#039;identit\u00e9. De plus, cela est important face \u00e0 la hausse constante des pertes li\u00e9es \u00e0 la fraude et \u00e0 l&#039;\u00e9volution des exigences en mati\u00e8re de contr\u00f4le.<\/p>\r\n\r\n\r\n<p>Ces s\u00e9ances comprennent\u00a0:<\/p>\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n\t<li><strong>Horodatage et journaux d&#039;\u00e9v\u00e9nements<\/strong>\u00a0pour chaque point de d\u00e9cision<\/li>\r\n\r\n\r\n\t<li><strong>Chemins d&#039;escalade et codes de motif<\/strong>\u00a0li\u00e9 aux r\u00e9sultats<\/li>\r\n\r\n\r\n\t<li><strong>Documents structur\u00e9s<\/strong>\u00a0pour les examens internes et les enqu\u00eates r\u00e9glementaires<\/li>\r\n<\/ul>\r\n\r\n\r\n<p>En enregistrant chaque parcours client du d\u00e9but \u00e0 la fin, ComplyCube aide les \u00e9quipes \u00e0 identifier les points de friction. Son outil de gestion des flux de travail KYC surveille les performances et optimise les processus pour am\u00e9liorer les taux de r\u00e9ussite et ainsi r\u00e9duire les faux positifs.<\/p>\r\n\r\n\r\n<h2 class=\"wp-block-heading\">D\u00e9ploiement flexible via API, SDK ou flux h\u00e9berg\u00e9<\/h2>\r\n\r\n\r\n<p>Pour soutenir\u00a0<a href=\"https:\/\/www.complycube.com\/fr\/developpeurs\/\">plusieurs gammes de produits et interfaces utilisateur,<\/a>\u00a0L&#039;outil d&#039;orchestration des flux de travail KYC de ComplyCube permet de cr\u00e9er des flux de travail d\u00e9ployables dans diff\u00e9rents environnements. Il garantit la coh\u00e9rence de la logique de v\u00e9rification sur tous les canaux d&#039;int\u00e9gration. Qu&#039;ils soient int\u00e9gr\u00e9s \u00e0 des applications mobiles ou h\u00e9berg\u00e9s en externe, les flux de travail peuvent \u00eatre mis en \u0153uvre par les organisations via\u00a0:<\/p>\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n\t<li><strong>Flux d&#039;int\u00e9gration h\u00e9berg\u00e9s<\/strong>, pr\u00eat \u00e0 \u00eatre lanc\u00e9 et personnalis\u00e9<\/li>\r\n\r\n\r\n\t<li><strong>SDK<\/strong>, pour les int\u00e9grer directement dans les applications web et mobiles<\/li>\r\n\r\n\r\n\t<li><strong>Apis<\/strong>, pour une int\u00e9gration profonde avec les syst\u00e8mes internes<\/li>\r\n<\/ul>\r\n\r\n\r\n<p>En r\u00e9sum\u00e9, cette flexibilit\u00e9 permet aux \u00e9quipes de conformit\u00e9 de g\u00e9rer les politiques de mani\u00e8re centralis\u00e9e. La personnalisation du processus d&#039;int\u00e9gration en fonction des diff\u00e9rents produits, types d&#039;utilisateurs et exigences garantit que chaque parcours client est conforme aux normes internes et aux obligations r\u00e9glementaires.<\/p>\r\n\r\n\r\n<h2 class=\"wp-block-heading\">\u00c0 propos de ComplyCube<\/h2>\r\n\r\n\r\n<p>Plus de 300 clients internationaux nous font confiance dans les secteurs de la fintech, des t\u00e9l\u00e9communications, des cryptomonnaies, des services gouvernementaux et financiers., <a href=\"https:\/\/www.complycube.com\/fr\/\">ComplyCube<\/a>\u00a0est une plateforme de conformit\u00e9 prim\u00e9e. Elle permet aux entreprises de concevoir, g\u00e9rer et optimiser l&#039;int\u00e9gration de leurs clients gr\u00e2ce \u00e0 des outils d&#039;orchestration de flux de travail KYC visuels et intuitifs, ainsi qu&#039;\u00e0 des API conviviales pour les d\u00e9veloppeurs. Reconnue dans le\u00a0<a href=\"https:\/\/www.complycube.com\/fr\/complycube-leader-de-laml-dans-le-rapport-g2-automne-2025\/?utm_medium=email&amp;_hsenc=p2ANqtz--HhXL-vIkbQRLaC0okykNtv5SKiEX89J_TpLcFrQuo3GrT3mKV72G0HtatAT_ltTX0-VbUzmCaGcL-9ruFgJJ8fVAgiSCjCqB4zrGv4q1S2v13pS4&amp;_hsmi=2&amp;utm_content=2&amp;utm_source=hs_email\">Rapport des dirigeants du G2 en mati\u00e8re de lutte contre le blanchiment d&#039;argent<\/a>\u00a0et figurant dans le classement FinCrimeTech50, la suite modulaire de ComplyCube couvre la v\u00e9rification de documents et biom\u00e9trique, le filtrage des sanctions et des PPE, ainsi que la logique de risque dynamique.\u00a0\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>ComplyCube lance un outil de workflow KYC sans code et en temps r\u00e9el. Cet outil d&#039;orchestration des workflows KYC permet des mises \u00e0 jour plus rapides des politiques, une int\u00e9gration coh\u00e9rente et des d\u00e9cisions conformes aux audits, offrant ainsi une orchestration compl\u00e8te du workflow KYC.<\/p>","protected":false},"author":35,"featured_media":31502,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[56],"class_list":["post-31500","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-announcements"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.complycube.com\/fr\/wp-json\/wp\/v2\/posts\/31500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.complycube.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.complycube.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.complycube.com\/fr\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.complycube.com\/fr\/wp-json\/wp\/v2\/comments?post=31500"}],"version-history":[{"count":1,"href":"https:\/\/www.complycube.com\/fr\/wp-json\/wp\/v2\/posts\/31500\/revisions"}],"predecessor-version":[{"id":31515,"href":"https:\/\/www.complycube.com\/fr\/wp-json\/wp\/v2\/posts\/31500\/revisions\/31515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.complycube.com\/fr\/wp-json\/wp\/v2\/media\/31502"}],"wp:attachment":[{"href":"https:\/\/www.complycube.com\/fr\/wp-json\/wp\/v2\/media?parent=31500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.complycube.com\/fr\/wp-json\/wp\/v2\/categories?post=31500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.complycube.com\/fr\/wp-json\/wp\/v2\/tags?post=31500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}