{"id":22305,"date":"2024-10-07T11:09:16","date_gmt":"2024-10-07T11:09:16","guid":{"rendered":"https:\/\/www.complycube.com\/?p=22305"},"modified":"2025-12-23T17:48:10","modified_gmt":"2025-12-23T17:48:10","slug":"que-es-el-fraude-de-identidad-sintetica","status":"publish","type":"post","link":"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/","title":{"rendered":"\u00bfQu\u00e9 es el fraude de identidad sint\u00e9tica?"},"content":{"rendered":"<p>Una pregunta que todas las empresas deber\u00edan hacerse en 2024 es: \u00bfqu\u00e9 es el fraude de identidad sint\u00e9tica? El fraude de identidad sint\u00e9tica implica combinar informaci\u00f3n real sobre la identidad de una persona con informaci\u00f3n falsa, creando una nueva identidad ficticia enga\u00f1osa. Es extremadamente dif\u00edcil detectar una identidad sint\u00e9tica, ya que los actores maliciosos suelen &quot;alimentarlas&quot; con el tiempo para construir gradualmente un perfil crediticio deseado. Esta forma de fraude de identidad se est\u00e1 volviendo cada vez m\u00e1s com\u00fan y las instituciones financieras, las aplicaciones de tecnolog\u00eda financiera y las plataformas comerciales suelen ser el objetivo. El aumento del fraude de identidad sint\u00e9tica tambi\u00e9n se ve respaldado por una cantidad cada vez mayor de informaci\u00f3n de identificaci\u00f3n personal que est\u00e1 f\u00e1cilmente disponible en la red oscura. Las empresas deben ser conscientes de los riesgos que conllevan estas identidades enga\u00f1osas y proteger sus organizaciones con soluciones integrales de IDV y KYC.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La anatom\u00eda de una identidad sint\u00e9tica<\/h2>\n\n\n\n<p>Una identidad sint\u00e9tica se crea combinando informaci\u00f3n personal identificable real y falsa, como el n\u00famero de la Seguridad Social, el nombre y la direcci\u00f3n. Las identidades sint\u00e9ticas se pueden utilizar para abrir cuentas bancarias, solicitar pr\u00e9stamos y realizar compras fraudulentas. Existen varias formas de fraude de identidad sint\u00e9tica, incluidas la compilaci\u00f3n de identidades y la manipulaci\u00f3n de identidades, que suelen utilizarse para crear un historial crediticio falso, lo que facilita la comisi\u00f3n de fraudes.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/images.surferseo.art\/ef14f94b-9c0c-4758-bd5a-9da703015a19.jpeg\" alt=\"\u00bfQu\u00e9 es el fraude de identidad sint\u00e9tica? \"\/><\/figure>\n\n\n\n<p>Una investigaci\u00f3n publicada a finales de 2023 destac\u00f3 el crecimiento del fraude de identidad sint\u00e9tica causado directamente por el desarrollo de la IA. Biometric Update inform\u00f3 que &quot;el fraude que involucra identidades generadas por IA ha aumentado un 17 por ciento en los \u00faltimos dos a\u00f1os, mientras que m\u00e1s de&nbsp;<a href=\"https:\/\/www.biometricupdate.com\/202311\/ai-speeds-synthetic-identity-fraud-enabling-human-like-interactions\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">dos tercios (76 por ciento)<\/a>&nbsp;de los profesionales financieros creen que sus empresas han aprobado a clientes que utilizan identidades sint\u00e9ticas\u201d. A medida que el fraude evoluciona debido a la disponibilidad de herramientas impulsadas por IA, las empresas tambi\u00e9n deben aprovechar estas herramientas para mantenerse un paso por delante. <\/p>\n\n\n\n<p>El fraude de identidad sint\u00e9tica suele ser un juego a largo plazo. A diferencia del robo de identidad tradicional, los estafadores sint\u00e9ticos suelen cultivar identidades a lo largo del tiempo y, gradualmente, construir un perfil crediticio que parece leg\u00edtimo. Este enfoque cuidadosamente planificado permite a los malos actores evitar la detecci\u00f3n inmediata. Con el tiempo, la identidad sint\u00e9tica parece ser cre\u00edble y los estafadores pueden solicitar pr\u00e9stamos o l\u00edneas de cr\u00e9dito m\u00e1s grandes antes de desaparecer. Por lo tanto, se ha convertido en un m\u00e9todo preferido por los estafadores, especialmente con la ayuda de identidades generadas por IA.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 es el fraude de identidad sint\u00e9tica y el impacto del robo de identidad?<\/h2>\n\n\n\n<p>Un informe de Transunion de finales de 2023 analiz\u00f3 el crecimiento y las tendencias del fraude digital, destacando que \u201clas violaciones de datos en EE. UU. aumentaron 15% al a\u00f1o&nbsp;<a href=\"https:\/\/statescoop.com\/synthetic-identity-fraud-data-breaches-transunion-report-2024\/\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">durante el a\u00f1o 2023<\/a>, con 54% de consumidores en 18 pa\u00edses y regiones que, seg\u00fan se informa, fueron blanco de intentos de fraude en l\u00ednea, correo electr\u00f3nico, llamadas telef\u00f3nicas o mensajes de texto entre septiembre y diciembre del a\u00f1o pasado\u201d. El aumento de las violaciones de datos, as\u00ed como la disponibilidad de datos confidenciales en l\u00ednea, ha provocado el aumento de las identidades sint\u00e9ticas. KPMG destac\u00f3 la gravedad del problema en 2022, se\u00f1alando en un art\u00edculo reciente que el fraude sint\u00e9tico es un problema de $6 mil millones de d\u00f3lares y \u201cel de m\u00e1s r\u00e1pido crecimiento\u201d.&nbsp;<a href=\"https:\/\/kpmg.com\/us\/en\/articles\/2022\/synthetic-identity-fraud.html\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">Delito financiero<\/a>&nbsp;\u201cen los Estados Unidos.\u201d<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>El de m\u00e1s r\u00e1pido crecimiento&nbsp;<a href=\"https:\/\/kpmg.com\/us\/en\/articles\/2022\/synthetic-identity-fraud.html\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">Delito financiero<\/a>&nbsp;En los Estados Unidos.<\/p>\n<\/blockquote>\n\n\n\n<p>El robo de identidad sint\u00e9tica puede tener un impacto significativo en las personas, incluido el da\u00f1o a su historial crediticio y p\u00e9rdidas financieras. Las v\u00edctimas pueden sufrir una divisi\u00f3n o fragmentaci\u00f3n de su historial crediticio, lo que dificulta la obtenci\u00f3n de cr\u00e9dito o pr\u00e9stamos. El robo de identidad sint\u00e9tica tambi\u00e9n puede tener un impacto significativo en las empresas, incluidas p\u00e9rdidas financieras y da\u00f1os a su reputaci\u00f3n. El impacto del robo de identidad sint\u00e9tica puede ser de gran alcance y afectar a varios sectores, incluidos los servicios financieros, la atenci\u00f3n m\u00e9dica y las entidades gubernamentales.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Se estima que <a href=\"https:\/\/legal.thomsonreuters.com\/en\/insights\/articles\/trends-in-synthetic-identity-fraud\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">95% de identidades sint\u00e9ticas<\/a> No se detectan durante el proceso de incorporaci\u00f3n.<\/p>\n<\/blockquote>\n\n\n\n<p>Dado que casi dos tercios de los profesionales financieros creen que su empresa ha aprobado a clientes que utilizan identidades sint\u00e9ticas, la mayor\u00eda de las empresas que no cuentan con procesos de verificaci\u00f3n exhaustivos corren un riesgo muy grave. Thomson Reuters sostiene que &quot;en las instituciones financieras, se estima que <a href=\"https:\/\/legal.thomsonreuters.com\/en\/insights\/articles\/trends-in-synthetic-identity-fraud\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">95% de identidades sint\u00e9ticas<\/a> No se detectan durante el proceso de incorporaci\u00f3n. En muchos sitios de comercio electr\u00f3nico y venta minorista, las p\u00e9rdidas debidas al robo de identidad sint\u00e9tica nunca se detectan o simplemente se descartan como un costo irrecuperable de la actividad comercial\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Protecci\u00f3n contra el fraude de identidad sint\u00e9tica<\/h2>\n\n\n\n<p>El problema con el fraude de identidad sint\u00e9tica es que detectarlo durante un proceso de solicitud\/incorporaci\u00f3n es extremadamente dif\u00edcil. KPMG afirma que \u201ca pesar de su tasa creciente, el fraude de identidad sint\u00e9tica sigue siendo casi <a href=\"https:\/\/kpmg.com\/us\/en\/articles\/2022\/synthetic-identity-fraud.html\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">imposible de marcar<\/a>&nbsp;Durante el proceso de solicitud, la capacidad de crear una cantidad ilimitada de identidades, junto con lo dif\u00edciles que son de detectar, hacen que el fraude de identidad sint\u00e9tica sea una opci\u00f3n popular entre los cibercriminales\u201d.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>A pesar de su tasa creciente, el fraude de identidad sint\u00e9tica sigue siendo casi... <a href=\"http:\/\/kpmg.com\/us\/en\/articles\/2022\/synthetic-identity-fraud.html\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">imposible de marcar<\/a>.<\/p>\n<\/blockquote>\n\n\n\n<p>Para protegerse contra el fraude de identidad sint\u00e9tica, las empresas deben invertir en herramientas avanzadas de verificaci\u00f3n de identidad y diligencia debida para detectar y prevenir el fraude de identidad sint\u00e9tica. Al emplear t\u00e9cnicas avanzadas de verificaci\u00f3n de identidad que incluyen verificaciones biom\u00e9tricas, autenticaci\u00f3n de documentos y comparaci\u00f3n de datos de m\u00faltiples fuentes, las empresas pueden detectar inconsistencias que indiquen identidades sint\u00e9ticas. Adem\u00e1s, la integraci\u00f3n del aprendizaje autom\u00e1tico para mejorar continuamente las capacidades de detecci\u00f3n ayuda a mantenerse a la vanguardia de las nuevas pr\u00e1cticas fraudulentas.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/images.surferseo.art\/f56d4632-69bb-4c58-bc59-ece8fe96165a.jpeg\" alt=\"detecci\u00f3n de deepfakes con inteligencia artificial, fraude de identidad sint\u00e9tica, \"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 se necesita?&nbsp;<strong>Comprobaciones de IDV con ComplyCube<\/strong><\/h2>\n\n\n\n<p>La detecci\u00f3n de identidades sint\u00e9ticas requiere m\u00e9todos de verificaci\u00f3n s\u00f3lidos y de m\u00faltiples capas, y las soluciones de verificaci\u00f3n biom\u00e9trica y de documentos de ComplyCube pueden proteger eficazmente a las empresas y a las personas contra esta amenaza. <\/p>\n\n\n\n<p>Su tecnolog\u00eda de detecci\u00f3n de vida garantiza que la persona que presenta la identidad est\u00e9 viva y presente, mitigando el riesgo de identidades generadas o falsificadas por IA. La integraci\u00f3n del reconocimiento facial y la validaci\u00f3n de documentos garantiza que los datos de identidad sean aut\u00e9nticos y no inventados. Al combinar an\u00e1lisis biom\u00e9tricos, de documentos y de comportamiento, las identidades sint\u00e9ticas se pueden detectar de forma temprana, lo que evita que los estafadores alimenten historiales crediticios falsos u obtengan acceso no autorizado. Algunas de las caracter\u00edsticas de sus soluciones incluyen:<\/p>\n\n\n\n<p><a href=\"https:\/\/www.complycube.com\/es\/soluciones\/aseguramiento-de-identidad\/verificacion-biometrica\/\"><strong>Robusto reconocimiento facial y similitud<\/strong><\/a><strong>:&nbsp;<\/strong>La tecnolog\u00eda avanzada de detecci\u00f3n de vida biom\u00e9trica certificada seg\u00fan ISO 30107-3 y PAD Nivel 2 de ComplyCube garantiza que la persona que presenta un documento de identidad coincida verdaderamente con los datos presentados. Su sistema de verificaci\u00f3n de identidad (IDV) combina an\u00e1lisis biom\u00e9trico y de comportamiento para brindar un proceso de verificaci\u00f3n de identidad altamente seguro y confiable, que ofrece un s\u00f3lido nivel de seguridad en la detecci\u00f3n de identidades fraudulentas o sint\u00e9ticas.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.complycube.com\/es\/soluciones\/aseguramiento-de-identidad\/verificacion-de-documentos\/\"><strong>Verificaci\u00f3n avanzada de documentos<\/strong><\/a><strong>:&nbsp;<\/strong>ComplyCube utiliza una combinaci\u00f3n de tecnolog\u00eda de inteligencia artificial y revisi\u00f3n por parte de expertos para verificar meticulosamente los documentos de identidad y garantizar que no hayan sido alterados, falsificados, copiados en l\u00ednea, vencidos o incluidos en listas negras. Este riguroso proceso es compatible con varios tipos de documentos, incluidos pasaportes, licencias de conducir, tarjetas de identificaci\u00f3n nacionales, permisos de residencia, sellos de visa y documentos de viaje, lo que proporciona una capa integral de protecci\u00f3n contra el fraude de identidad.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/images.surferseo.art\/cee9bf8f-b887-4aab-8418-29d31294d833.jpeg\" alt=\"\u00bfQu\u00e9 es el fraude de identidad sint\u00e9tica? Estados Unidos es v\u00edctima de un fraude de identidad sint\u00e9tica, la Reserva Federal se ve afectada. El fraude de m\u00e1s r\u00e1pido crecimiento en Estados Unidos.\"\/><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.complycube.com\/es\/soluciones\/cumplimiento-de-la-debida-diligencia\/conozca-a-su-cliente\/deteccion-de-vida\/\"><strong>Detecci\u00f3n experta de vida<\/strong><\/a><strong>:&nbsp;<\/strong>Su software de detecci\u00f3n de vida PAD-Level 2 con tecnolog\u00eda de inteligencia artificial confirma con precisi\u00f3n la presencia real del cliente y detecta a los impostores. Al incorporar tecnolog\u00eda avanzada contra la suplantaci\u00f3n de identidad, ComplyCube protege eficazmente a las empresas incluso de los intentos de fraude m\u00e1s sofisticados.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.complycube.com\/es\/soluciones\/aseguramiento-de-identidad\/autenticacion-del-cliente\/\"><strong>Registro biom\u00e9trico sin inconvenientes<\/strong><\/a><strong>:&nbsp;<\/strong>Una tecnolog\u00eda de captura facial guiada de primer nivel que garantiza una autenticaci\u00f3n perfecta para acceder a finanzas, telecomunicaciones, viajes, servicios empresariales y m\u00e1s.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Proteja su negocio hoy<\/h2>\n\n\n\n<p>El fraude de identidad sint\u00e9tica es una preocupaci\u00f3n creciente, con p\u00e9rdidas de miles de millones de d\u00f3lares. Es esencial comprender la anatom\u00eda de una identidad sint\u00e9tica y el impacto del robo de identidad sint\u00e9tica. La protecci\u00f3n contra el fraude de identidad sint\u00e9tica requiere herramientas avanzadas de verificaci\u00f3n de identidad y diligencia debida, as\u00ed como un proceso s\u00f3lido de verificaci\u00f3n de identidad.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/images.surferseo.art\/2dc7299d-f665-4a7b-b4fe-d4478eb94ea9.jpeg\" alt=\"Detecci\u00f3n de deepfakes con inteligencia artificial\"\/><\/figure>\n\n\n\n<p>Al comprender el papel de la tecnolog\u00eda en el fraude de identidad sint\u00e9tica e implementar estrategias de protecci\u00f3n empresarial, las personas y las empresas pueden minimizar el riesgo de fraude de identidad sint\u00e9tica.<\/p>\n\n\n\n<p>Contacte con uno de los ComplyCube <a href=\"https:\/\/www.complycube.com\/es\/contacto\/contactar-con-ventas\/\" title=\"\">expertos en cumplimiento<\/a> y ponga en pr\u00e1ctica medidas para proteger su organizaci\u00f3n hoy.&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Las empresas se enfrentan a la creciente amenaza del fraude de identidad sint\u00e9tica. Se necesita una verificaci\u00f3n biom\u00e9trica sofisticada con detecci\u00f3n de deepfakes mediante inteligencia artificial y una verificaci\u00f3n avanzada de documentos para proteger a las empresas contra las pr\u00e1cticas fraudulentas en evoluci\u00f3n.<\/p>","protected":false},"author":24,"featured_media":22306,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"footnotes":""},"categories":[6],"tags":[53],"class_list":["post-22305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guides","tag-identity-verification"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"What is synthetic identity fraud? Protect your business from deceptive forms of fraud with sophisticated ai deepfake detection\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Sofia Daley\"\/>\n\t<meta name=\"google-site-verification\" content=\"9nwsC3BxNQT0rN_dh5xNnCBQI6EVMaGEtvfky-IUUgQ\" \/>\n\t<meta name=\"msvalidate.01\" content=\"6787C3F0846FBE039FCD4064ECED4F6A\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"ComplyCube | Identity Verification, KYC &amp; AML for Global Compliance\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"What is Synthetic Identity Fraud?\" \/>\n\t\t<meta property=\"og:description\" content=\"Businesses face the growing threat of synthetic identity fraud. Sophisticated biometric verification with ai deepfake detection and an advanced document check is needed to safeguard businesses against evolving fraudulent practices.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.complycube.com\/wp-content\/uploads\/2024\/10\/header-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.complycube.com\/wp-content\/uploads\/2024\/10\/header-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1443\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-10-07T11:09:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-12-23T17:48:10+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ComplyCube\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@ComplyCube\" \/>\n\t\t<meta name=\"twitter:title\" content=\"What is Synthetic Identity Fraud?\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Businesses face the growing threat of synthetic identity fraud. Sophisticated biometric verification with ai deepfake detection and an advanced document check is needed to safeguard businesses against evolving fraudulent practices.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@ComplyCube\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.complycube.com\/wp-content\/uploads\/2024\/10\/header-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/what-is-synthetic-identity-fraud\\\/#blogposting\",\"name\":\"What is Synthetic Identity Fraud? | ComplyCube\",\"headline\":\"What is Synthetic Identity Fraud?\",\"author\":{\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/author\\\/sofia-d\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.complycube.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/header-1.jpg\",\"width\":2560,\"height\":1443,\"caption\":\"create a synthetic identity, synthetic identity fraud, ai deepfake detection,\"},\"datePublished\":\"2024-10-07T11:09:16+00:00\",\"dateModified\":\"2025-12-23T17:48:10+00:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/what-is-synthetic-identity-fraud\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/what-is-synthetic-identity-fraud\\\/#webpage\"},\"articleSection\":\"Guides, Identity Verification\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/what-is-synthetic-identity-fraud\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/category\\\/guides\\\/#listItem\",\"name\":\"Guides\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/category\\\/guides\\\/#listItem\",\"position\":2,\"name\":\"Guides\",\"item\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/category\\\/guides\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/what-is-synthetic-identity-fraud\\\/#listItem\",\"name\":\"What is Synthetic Identity Fraud?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/what-is-synthetic-identity-fraud\\\/#listItem\",\"position\":3,\"name\":\"What is Synthetic Identity Fraud?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/category\\\/guides\\\/#listItem\",\"name\":\"Guides\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/#organization\",\"name\":\"ComplyCube\",\"description\":\"Identity Verification, KYC & AML for Global Compliance\",\"url\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/\",\"telephone\":\"+442032861575\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":0,\"maxValue\":200},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.complycube.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/ComplyCube-Square-125-x-125.png\",\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/what-is-synthetic-identity-fraud\\\/#organizationLogo\",\"width\":125,\"height\":125,\"caption\":\"ComplyCube Square Logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/what-is-synthetic-identity-fraud\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ComplyCube\",\"https:\\\/\\\/x.com\\\/ComplyCube\",\"https:\\\/\\\/www.instagram.com\\\/complycube\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@complycube\",\"https:\\\/\\\/linkedin.com\\\/company\\\/ComplyCube\"],\"address\":{\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"30 Churchill Place, Canary Wharf\",\"postalCode\":\"E14 5RE\",\"addressLocality\":\"London\",\"addressCountry\":\"GB\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/author\\\/sofia-d\\\/#author\",\"url\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/author\\\/sofia-d\\\/\",\"name\":\"Sofia Daley\",\"description\":\"Sofia Daley is a dynamic Content Marketing Executive at ComplyCube, renowned for her expertise in growth marketing, social media strategy, and compliance-driven content creation. With strong knowledge of AML and KYC compliance, Sofia designs impactful narratives that empower organisations to scale responsibly while fostering trust and ensuring strict regulatory adherence. Her proven track record includes building a TikTok following of over 140K and a Meta audience of 15K, generating $30,000+ in monthly sales through engaging, user-focused content. Sofia\\u2019s ability to integrate AML and KYC frameworks into customer-facing materials ensures businesses not only meet compliance standards but also enhance credibility and customer trust. In addition to her marketing expertise, Sofia is the award-winning author of The Bird Who Could Not Sing, a children\\u2019s book widely praised for its creativity and storytelling. She complements her professional accomplishments with a strong academic foundation, holding a degree in English Literature from UCL and a Professional Certificate in Digital Marketing from Imperial College Business School. At ComplyCube, Sofia combines her growth-oriented mindset, compliance knowledge, and creative storytelling abilities to deliver innovative content solutions that enhance customer experiences and drive sustainable growth.\",\"jobTitle\":\"Content Marketing Executive\",\"alumniOf\":[{\"@type\":\"EducationalOrganization\",\"name\":\"University College London\",\"sameAs\":\"https:\\\/\\\/www.ucl.ac.uk\"},{\"@type\":\"EducationalOrganization\",\"name\":\"Imperial Business School\",\"sameAs\":\"https:\\\/\\\/www.imperial.ac.uk\\\/business-school\\\/\"}],\"knowsAbout\":[{\"@type\":\"Thing\",\"name\":\"Regulatory compliance\",\"url\":\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Regulatory_compliance\"},{\"@type\":\"Thing\",\"name\":\"Know your customer\",\"url\":\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Know_your_customer\"},{\"@type\":\"Thing\",\"name\":\"Growth hacking\",\"url\":\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Growth_hacking\"},{\"@type\":\"Thing\",\"name\":\"FinTech\",\"url\":\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Fintech\"}],\"knowsLanguage\":[\"English\",\"Spanish\"],\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/what-is-synthetic-identity-fraud\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.complycube.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/1715852152509.jpeg\",\"width\":400,\"height\":400}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/what-is-synthetic-identity-fraud\\\/#webpage\",\"url\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/what-is-synthetic-identity-fraud\\\/\",\"name\":\"What is Synthetic Identity Fraud? | ComplyCube\",\"description\":\"What is synthetic identity fraud? Protect your business from deceptive forms of fraud with sophisticated ai deepfake detection\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/what-is-synthetic-identity-fraud\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/author\\\/sofia-d\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/author\\\/sofia-d\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.complycube.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/header-1.jpg\",\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/what-is-synthetic-identity-fraud\\\/#mainImage\",\"width\":2560,\"height\":1443,\"caption\":\"create a synthetic identity, synthetic identity fraud, ai deepfake detection,\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/what-is-synthetic-identity-fraud\\\/#mainImage\"},\"datePublished\":\"2024-10-07T11:09:16+00:00\",\"dateModified\":\"2025-12-23T17:48:10+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/\",\"name\":\"ComplyCube\",\"description\":\"Identity Verification, KYC & AML for Global Compliance\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.complycube.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>What is Synthetic Identity Fraud? | ComplyCube<\/title>\n\n","aioseo_head_json":{"title":"\u00bfQu\u00e9 es el fraude de identidad sint\u00e9tica? | ComplyCube","description":"\u00bfQu\u00e9 es el fraude de identidad sint\u00e9tica? Proteja su empresa de formas enga\u00f1osas de fraude con la sofisticada detecci\u00f3n de deepfakes con inteligencia artificial","canonical_url":"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"9nwsC3BxNQT0rN_dh5xNnCBQI6EVMaGEtvfky-IUUgQ","msvalidate.01":"6787C3F0846FBE039FCD4064ECED4F6A","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/#blogposting","name":"What is Synthetic Identity Fraud? | ComplyCube","headline":"What is Synthetic Identity Fraud?","author":{"@id":"https:\/\/www.complycube.com\/es\/author\/sofia-d\/#author"},"publisher":{"@id":"https:\/\/www.complycube.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.complycube.com\/wp-content\/uploads\/2024\/10\/header-1.jpg","width":2560,"height":1443,"caption":"create a synthetic identity, synthetic identity fraud, ai deepfake detection,"},"datePublished":"2024-10-07T11:09:16+00:00","dateModified":"2025-12-23T17:48:10+00:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/#webpage"},"isPartOf":{"@id":"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/#webpage"},"articleSection":"Guides, Identity Verification"},{"@type":"BreadcrumbList","@id":"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.complycube.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/www.complycube.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.complycube.com\/es\/category\/guides\/#listItem","name":"Guides"}},{"@type":"ListItem","@id":"https:\/\/www.complycube.com\/es\/category\/guides\/#listItem","position":2,"name":"Guides","item":"https:\/\/www.complycube.com\/es\/category\/guides\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/#listItem","name":"What is Synthetic Identity Fraud?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.complycube.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/#listItem","position":3,"name":"What is Synthetic Identity Fraud?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.complycube.com\/es\/category\/guides\/#listItem","name":"Guides"}}]},{"@type":"Organization","@id":"https:\/\/www.complycube.com\/es\/#organization","name":"ComplyCube","description":"Identity Verification, KYC & AML for Global Compliance","url":"https:\/\/www.complycube.com\/es\/","telephone":"+442032861575","numberOfEmployees":{"@type":"QuantitativeValue","minValue":0,"maxValue":200},"logo":{"@type":"ImageObject","url":"https:\/\/www.complycube.com\/wp-content\/uploads\/2022\/09\/ComplyCube-Square-125-x-125.png","@id":"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/#organizationLogo","width":125,"height":125,"caption":"ComplyCube Square Logo"},"image":{"@id":"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/ComplyCube","https:\/\/x.com\/ComplyCube","https:\/\/www.instagram.com\/complycube\/","https:\/\/www.youtube.com\/@complycube","https:\/\/linkedin.com\/company\/ComplyCube"],"address":{"@id":"https:\/\/www.complycube.com\/es\/#postaladdress","@type":"PostalAddress","streetAddress":"30 Churchill Place, Canary Wharf","postalCode":"E14 5RE","addressLocality":"London","addressCountry":"GB"}},{"@type":"Person","@id":"https:\/\/www.complycube.com\/es\/author\/sofia-d\/#author","url":"https:\/\/www.complycube.com\/es\/author\/sofia-d\/","name":"Sofia Daley","description":"Sofia Daley is a dynamic Content Marketing Executive at ComplyCube, renowned for her expertise in growth marketing, social media strategy, and compliance-driven content creation. With strong knowledge of AML and KYC compliance, Sofia designs impactful narratives that empower organisations to scale responsibly while fostering trust and ensuring strict regulatory adherence. Her proven track record includes building a TikTok following of over 140K and a Meta audience of 15K, generating $30,000+ in monthly sales through engaging, user-focused content. Sofia\u2019s ability to integrate AML and KYC frameworks into customer-facing materials ensures businesses not only meet compliance standards but also enhance credibility and customer trust. In addition to her marketing expertise, Sofia is the award-winning author of The Bird Who Could Not Sing, a children\u2019s book widely praised for its creativity and storytelling. She complements her professional accomplishments with a strong academic foundation, holding a degree in English Literature from UCL and a Professional Certificate in Digital Marketing from Imperial College Business School. At ComplyCube, Sofia combines her growth-oriented mindset, compliance knowledge, and creative storytelling abilities to deliver innovative content solutions that enhance customer experiences and drive sustainable growth.","jobTitle":"Content Marketing Executive","alumniOf":[{"@type":"EducationalOrganization","name":"University College London","sameAs":"https:\/\/www.ucl.ac.uk"},{"@type":"EducationalOrganization","name":"Imperial Business School","sameAs":"https:\/\/www.imperial.ac.uk\/business-school\/"}],"knowsAbout":[{"@type":"Thing","name":"Regulatory compliance","url":"https:\/\/en.wikipedia.org\/wiki\/Regulatory_compliance"},{"@type":"Thing","name":"Know your customer","url":"https:\/\/en.wikipedia.org\/wiki\/Know_your_customer"},{"@type":"Thing","name":"Growth hacking","url":"https:\/\/en.wikipedia.org\/wiki\/Growth_hacking"},{"@type":"Thing","name":"FinTech","url":"https:\/\/en.wikipedia.org\/wiki\/Fintech"}],"knowsLanguage":["English","Spanish"],"image":{"@type":"ImageObject","@id":"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/#authorImage","url":"https:\/\/www.complycube.com\/wp-content\/uploads\/2024\/12\/1715852152509.jpeg","width":400,"height":400}},{"@type":"WebPage","@id":"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/#webpage","url":"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/","name":"What is Synthetic Identity Fraud? | ComplyCube","description":"What is synthetic identity fraud? Protect your business from deceptive forms of fraud with sophisticated ai deepfake detection","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.complycube.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/#breadcrumblist"},"author":{"@id":"https:\/\/www.complycube.com\/es\/author\/sofia-d\/#author"},"creator":{"@id":"https:\/\/www.complycube.com\/es\/author\/sofia-d\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.complycube.com\/wp-content\/uploads\/2024\/10\/header-1.jpg","@id":"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/#mainImage","width":2560,"height":1443,"caption":"create a synthetic identity, synthetic identity fraud, ai deepfake detection,"},"primaryImageOfPage":{"@id":"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/#mainImage"},"datePublished":"2024-10-07T11:09:16+00:00","dateModified":"2025-12-23T17:48:10+00:00"},{"@type":"WebSite","@id":"https:\/\/www.complycube.com\/es\/#website","url":"https:\/\/www.complycube.com\/es\/","name":"ComplyCube","description":"Identity Verification, KYC & AML for Global Compliance","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.complycube.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"ComplyCube | Identity Verification, KYC &amp; AML for Global Compliance","og:type":"article","og:title":"What is Synthetic Identity Fraud?","og:description":"Businesses face the growing threat of synthetic identity fraud. Sophisticated biometric verification with ai deepfake detection and an advanced document check is needed to safeguard businesses against evolving fraudulent practices.","og:url":"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/","og:image":"https:\/\/www.complycube.com\/wp-content\/uploads\/2024\/10\/header-1.jpg","og:image:secure_url":"https:\/\/www.complycube.com\/wp-content\/uploads\/2024\/10\/header-1.jpg","og:image:width":"2560","og:image:height":"1443","article:published_time":"2024-10-07T11:09:16+00:00","article:modified_time":"2025-12-23T17:48:10+00:00","article:publisher":"https:\/\/www.facebook.com\/ComplyCube","twitter:card":"summary","twitter:site":"@ComplyCube","twitter:title":"What is Synthetic Identity Fraud?","twitter:description":"Businesses face the growing threat of synthetic identity fraud. Sophisticated biometric verification with ai deepfake detection and an advanced document check is needed to safeguard businesses against evolving fraudulent practices.","twitter:creator":"@ComplyCube","twitter:image":"https:\/\/www.complycube.com\/wp-content\/uploads\/2024\/10\/header-1.jpg"},"aioseo_meta_data":{"post_id":"22305","title":null,"description":"\u00bfQu\u00e9 es el fraude de identidad sint\u00e9tica? Proteja su empresa de formas enga\u00f1osas de fraude con la sofisticada detecci\u00f3n de deepfakes con inteligencia artificial","keywords":null,"keyphrases":{"focus":{"keyphrase":"what is synthetic identity fraud","score":74,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":6,"maxScore":9,"error":1,"length":5},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[{"keyphrase":"synthetic identity fraud","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":3},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},{"keyphrase":"ai deepfake detection","score":67,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":3},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":"#post_title","og_description":"#post_excerpt","og_object_type":"default","og_image_type":"featured","og_image_url":"https:\/\/www.complycube.com\/wp-content\/uploads\/2024\/10\/header-1.jpg","og_image_width":"2560","og_image_height":"1443","og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"featured","twitter_image_url":"https:\/\/www.complycube.com\/wp-content\/uploads\/2024\/10\/header-1.jpg","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":"#post_title","twitter_description":"#post_excerpt","schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-06-21 18:34:21","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2024-10-07 09:53:22","updated":"2026-06-21 18:34:21","focus_keyword":"what is synthetic identity fraud","additional_keywords":[{"word":"synthetic identity fraud","score":100},{"word":"ai deepfake detection","score":67}],"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.complycube.com\/es\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.complycube.com\/es\/category\/guides\/\" title=\"Guides\">Guides<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tWhat is Synthetic Identity Fraud?\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.complycube.com\/es\/"},{"label":"Guides","link":"https:\/\/www.complycube.com\/es\/category\/guides\/"},{"label":"What is Synthetic Identity Fraud?","link":"https:\/\/www.complycube.com\/es\/what-is-synthetic-identity-fraud\/"}],"_links":{"self":[{"href":"https:\/\/www.complycube.com\/es\/wp-json\/wp\/v2\/posts\/22305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.complycube.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.complycube.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.complycube.com\/es\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.complycube.com\/es\/wp-json\/wp\/v2\/comments?post=22305"}],"version-history":[{"count":8,"href":"https:\/\/www.complycube.com\/es\/wp-json\/wp\/v2\/posts\/22305\/revisions"}],"predecessor-version":[{"id":30741,"href":"https:\/\/www.complycube.com\/es\/wp-json\/wp\/v2\/posts\/22305\/revisions\/30741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.complycube.com\/es\/wp-json\/wp\/v2\/media\/22306"}],"wp:attachment":[{"href":"https:\/\/www.complycube.com\/es\/wp-json\/wp\/v2\/media?parent=22305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.complycube.com\/es\/wp-json\/wp\/v2\/categories?post=22305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.complycube.com\/es\/wp-json\/wp\/v2\/tags?post=22305"}],"curies":[{"name":"Gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}